{"id":9093,"date":"2020-11-10T00:26:24","date_gmt":"2020-11-10T03:26:24","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=9093"},"modified":"2020-11-10T00:26:25","modified_gmt":"2020-11-10T03:26:25","slug":"presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/","title":{"rendered":"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA.jpg\" alt=\"\" class=\"wp-image-9083\" width=\"356\" height=\"213\" srcset=\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA.jpg 498w, https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-300x180.jpg 300w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><figcaption><strong><em>Vander Costa<\/em><\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p>La Confederaci\u00f3n Nacional de Transportes (CNT), entidad empresarial patronal que agrupa a las federaciones regionales y sindicatos del transporte de todo el pa\u00eds present\u00f3, a principios de noviembre, el documento Pilares de la Reforma Tributaria.<\/p>\n\n\n\n<p>La publicaci\u00f3n, que se puede descargar a trav\u00e9s de un enlace al final de este art\u00edculo (solamente en portugu\u00e9s), presenta y explica las diez condiciones defendidas por el sector del transporte para la simplificaci\u00f3n y modernizaci\u00f3n del sistema tributario brasile\u00f1o, independientemente de las propuestas puestas a discusi\u00f3n en el Congreso Nacional.<\/p>\n\n\n\n<p><strong>LOS DIEZ PUNTOS<\/strong><\/p>\n\n\n\n<p>Los diez puntos son los siguientes: 1) No aumento de la carga tributaria global y sectorial; 2) \u201cCreditamento\u201d total para insumos de transporte; 3) Rechazo de impuestos selectivos con una carga para el sector del transporte; 4) N\u00f3mina como cr\u00e9dito; 5) Exenci\u00f3n total a las exportaciones; 6) Trato sectorial diferenciado; 7) Trato diferenciado en el sector de infraestructura; 8) Mantenimiento del servicio social y aprendizaje sectorial; 9) Necesidad de transparencia de datos; 10) Per\u00edodo de transici\u00f3n ajustado.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-CAPA-RECOMENDA\u00c7\u00d5ES-CNT-REFORMA-TRIBUT\u00c1RIA.jpg\" alt=\"\" class=\"wp-image-9090\" width=\"230\" height=\"319\" srcset=\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-CAPA-RECOMENDA\u00c7\u00d5ES-CNT-REFORMA-TRIBUT\u00c1RIA.jpg 346w, https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-CAPA-RECOMENDA\u00c7\u00d5ES-CNT-REFORMA-TRIBUT\u00c1RIA-216x300.jpg 216w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/figure><\/div>\n\n\n\n<p>El documento muestra que, para la Confederaci\u00f3n Nacional de Transporte, es fundamental garantizar que no se incremente la carga fiscal global y sectorial, adem\u00e1s del cr\u00e9dito total para insumos de transporte. La entidad tambi\u00e9n defiende que los impuestos selectivos que gravan al sector del transporte no incluyen ninguna de las propuestas.<\/p>\n\n\n\n<p><strong>IMPORTANCIA DE CNT<\/strong><\/p>\n\n\n\n<p>La Confederaci\u00f3n Nacional de Transporte (CNT) fue creada en 1954 y califica como la m\u00e1xima representaci\u00f3n del transporte brasile\u00f1o. La instituci\u00f3n agrupa a 26 federaciones y cuatro sindicatos nacionales. Hay 155 mil empresas y 2,2 millones de puestos de trabajo generados.<\/p>\n\n\n\n<p>En la composici\u00f3n del Sistema CNT, la instituci\u00f3n tambi\u00e9n gestiona el SEST SENAT (Servicio de Transporte Social y Servicio Nacional de Aprendizaje en Transporte) y el ITL (Instituto de Transporte y Log\u00edstica), \u00f3rganos mencionados en el octavo punto del texto. <\/p>\n\n\n\n<p>El presidente de la CNT, Vander Costa, dice que el sector apoya una amplia reforma tributaria que aporte justicia, neutralidad y sencillez al sistema tributario nacional. \u201cLa CNT est\u00e1 comprometida con el desarrollo socioecon\u00f3mico de Brasil, pero se ve en el deber de defender los intereses de los transportistas y asegurar que las propuestas se perfeccionen. El sistema actual tiene distorsiones estructurales que dificultan la competitividad de las empresas y el crecimiento econ\u00f3mico del pa\u00eds\u201d.<\/p>\n\n\n\n<p><strong><em><a href=\"https:\/\/mobilitas.lat\/201108-texto-251-recomendacoes-cnt-pdf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Acceder al documento (solo en portugu\u00e9s)<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Confederaci\u00f3n Nacional de Transportes (CNT), entidad empresarial patronal que agrupa a las federaciones regionales y sindicatos del transporte de todo el pa\u00eds present\u00f3, a principios de noviembre, el documento Pilares de la Reforma Tributaria. La publicaci\u00f3n, que se puede descargar a trav\u00e9s de un enlace al final de este art\u00edculo (solamente en portugu\u00e9s), presenta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287,307],"tags":[387,1352,1353],"class_list":["post-9093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","category-puntos-de-vista","tag-cnt-es","tag-reforma-tributaria","tag-vander-costa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"La Confederaci\u00f3n Nacional de Transportes (CNT), entidad empresarial patronal que agrupa a las federaciones regionales y sindicatos del transporte de todo el pa\u00eds present\u00f3, a principios de noviembre, el documento Pilares de la Reforma Tributaria. La publicaci\u00f3n, que se puede descargar a trav\u00e9s de un enlace al final de este art\u00edculo (solamente en portugu\u00e9s), presenta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-10T03:26:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-10T03:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"498\" \/>\n\t<meta property=\"og:image:height\" content=\"294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios\",\"datePublished\":\"2020-11-10T03:26:24+00:00\",\"dateModified\":\"2020-11-10T03:26:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\"},\"wordCount\":435,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg\",\"keywords\":[\"CNT\",\"REFORMA TRIBUT\u00c1RIA\",\"VANDER COSTA\"],\"articleSection\":[\"Notas\",\"Puntos de Vista\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\",\"name\":\"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg\",\"datePublished\":\"2020-11-10T03:26:24+00:00\",\"dateModified\":\"2020-11-10T03:26:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg\",\"width\":498,\"height\":294},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/","og_locale":"es_ES","og_type":"article","og_title":"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios | Mobilitas","og_description":"La Confederaci\u00f3n Nacional de Transportes (CNT), entidad empresarial patronal que agrupa a las federaciones regionales y sindicatos del transporte de todo el pa\u00eds present\u00f3, a principios de noviembre, el documento Pilares de la Reforma Tributaria. La publicaci\u00f3n, que se puede descargar a trav\u00e9s de un enlace al final de este art\u00edculo (solamente en portugu\u00e9s), presenta [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/","og_site_name":"Mobilitas","article_published_time":"2020-11-10T03:26:24+00:00","article_modified_time":"2020-11-10T03:26:25+00:00","og_image":[{"width":498,"height":294,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg","type":"image\/jpeg"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios","datePublished":"2020-11-10T03:26:24+00:00","dateModified":"2020-11-10T03:26:25+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/"},"wordCount":435,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg","keywords":["CNT","REFORMA TRIBUT\u00c1RIA","VANDER COSTA"],"articleSection":["Notas","Puntos de Vista"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/","url":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/","name":"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg","datePublished":"2020-11-10T03:26:24+00:00","dateModified":"2020-11-10T03:26:25+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2020\/11\/MOBILITAS-FOTO-VANDER-COSTA-2.jpg","width":498,"height":294},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2020\/11\/10\/presidida-por-vander-costa-la-cnt-entidad-maxima-de-empresas-de-transporte-en-brasil-lanza-documento-en-defensa-de-reforma-tributaria-sin-aumento-de-impuestos-y-con-estimulo-a-los-negocios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"Presidida por Vander Costa, la CNT, entidad m\u00e1xima de empresas de transporte en Brasil, lanza documento en defensa de reforma tributaria sin aumento de impuestos y con est\u00edmulo a los negocios"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/9093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=9093"}],"version-history":[{"count":4,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/9093\/revisions"}],"predecessor-version":[{"id":9097,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/9093\/revisions\/9097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/9099"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=9093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=9093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=9093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}