{"id":3625,"date":"2018-12-23T22:53:48","date_gmt":"2018-12-24T00:53:48","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=3625"},"modified":"2018-12-23T22:56:38","modified_gmt":"2018-12-24T00:56:38","slug":"listo-para-la-interconexion-con-el-metro-de-quito","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/","title":{"rendered":"Listo para la interconexi\u00f3n con el Metro de Quito"},"content":{"rendered":"\n<p>El gobierno de Quito destaca que el sistema de transporte metropolitano Troleb\u00fas,\nque cumple 23 a\u00f1os, est\u00e1 listo para su interconexi\u00f3n con el metro que se va a\ninaugurar el 2019. &nbsp;Durante las \u00faltimas\ndos d\u00e9cadas, el Trole, como es llamado, &nbsp;se consolid\u00f3 como un elemento fundamental para\nel desarrollo de la capital ecuatoriana y como un distintivo de la identidad\nquite\u00f1a.<\/p>\n\n\n\n<p>El Trole inici\u00f3 sus operaciones el 17 de diciembre de 1995\nconvirti\u00e9ndose en el primer sistema de autob\u00fas de tr\u00e1nsito r\u00e1pido del Ecuador.<\/p>\n\n\n\n<p>La operaci\u00f3n empez\u00f3 desde la Estaci\u00f3n el Recreo hasta la calle\nEsmeraldas, en el Centro Hist\u00f3rico movilizando a 50.000 pasajeros diariamente.\nPosteriormente, en 1998, la operaci\u00f3n se extendi\u00f3 hasta la avenida Col\u00f3n y m\u00e1s\nadelante hasta La Y. Hoy, el sistema moviliza diariamente a m\u00e1s de 900 000\npasajeros<\/p>\n\n\n\n<p>En el 2015 se adquirieron 40 unidades articuladas 80 buses biarticuladas\ny se reconstruyeron las paradas del Troleb\u00fas y la Ecov\u00eda y, adicionalmente, se\nampl\u00edo el servicio hasta la terminal Guaman\u00ed.<\/p>\n\n\n\n<p>En 2018 entr\u00f3 en operaci\u00f3n la nueva terminal multimodal El Labrador que\nel pr\u00f3ximo a\u00f1o conectar\u00e1 al Troleb\u00fas el Metro de Quito.<\/p>\n\n\n\n<p><strong>SISTEMA DE INFORMACI\u00d3N AL\nUSUARIO<\/strong><\/p>\n\n\n\n<p>El gobierno quite\u00f1o subraya que el Trole se convirti\u00f3 en la columna\nvertebral del transporte capitalino. En la actualidad, el Trole conecta a\nCarcel\u00e9n con Quitumbe y a Empresa P\u00fablica Metropolitana de Transporte de\nPasajeros de Quito (EPMTP), instituci\u00f3n encargada de administrar este corredor,\ntiene en marcha un proceso de modernizaci\u00f3n del servicio para la multimodalidad\nque se aplicar\u00e1 con el Metro de Quito. <\/p>\n\n\n\n<p>Esto incluye la implementaci\u00f3n del Sistema de Informaci\u00f3n al Usuario\n(SIU), que se refiere a la tecnolog\u00eda para brindar una oportuna, confiable y adecuada\ninformaci\u00f3n a los usuarios del transporte p\u00fablico.<\/p>\n\n\n\n<p>El Sistema de Informaci\u00f3n al Usuario (SIU) se est\u00e1 implementando a\ntrav\u00e9s de pantallas que informan en tiempo real la hora de llegada de las\nunidades. Esto con el objetivo de mejorar el servicio y que la ciudadan\u00eda\nconozca de primera mano los horarios y frecuencia de las rutas.<\/p>\n\n\n\n<p><strong>\u2018SOCIOS EN EL VIAJE\u2019<\/strong><\/p>\n\n\n\n<p>Adem\u00e1s, se implement\u00f3 la Campa\u00f1a \u2018Somos Socios en el Viaje\u2019 para\nfomentar en los usuarios y en los funcionarios de la EPMTP las buenas pr\u00e1cticas\npara el uso y buena atenci\u00f3n en el sistema de transporte. Se busca que los\nusuarios se empoderen del transporte p\u00fablico y tomen actitudes positivas que\nfaciliten la movilidad dentro del sistema como, por ejemplo: hacer filas,\nrespetar el ingreso y salida de pasajeros de las unidades, no aglutinarse en\nlas puertas, mantener limpias las unidades, entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Quito destaca que el sistema de transporte metropolitano Troleb\u00fas, que cumple 23 a\u00f1os, est\u00e1 listo para su interconexi\u00f3n con el metro que se va a inaugurar el 2019. &nbsp;Durante las \u00faltimas dos d\u00e9cadas, el Trole, como es llamado, &nbsp;se consolid\u00f3 como un elemento fundamental para el desarrollo de la capital ecuatoriana y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287],"tags":[775,782],"class_list":["post-3625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","tag-destaque","tag-trolebus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Listo para la interconexi\u00f3n con el Metro de Quito | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Listo para la interconexi\u00f3n con el Metro de Quito | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"El gobierno de Quito destaca que el sistema de transporte metropolitano Troleb\u00fas, que cumple 23 a\u00f1os, est\u00e1 listo para su interconexi\u00f3n con el metro que se va a inaugurar el 2019. &nbsp;Durante las \u00faltimas dos d\u00e9cadas, el Trole, como es llamado, &nbsp;se consolid\u00f3 como un elemento fundamental para el desarrollo de la capital ecuatoriana y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-24T00:53:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-24T00:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"569\" \/>\n\t<meta property=\"og:image:height\" content=\"309\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"Listo para la interconexi\u00f3n con el Metro de Quito\",\"datePublished\":\"2018-12-24T00:53:48+00:00\",\"dateModified\":\"2018-12-24T00:56:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\"},\"wordCount\":465,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png\",\"keywords\":[\"destaque\",\"TROLEBUS\"],\"articleSection\":[\"Notas\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\",\"name\":\"Listo para la interconexi\u00f3n con el Metro de Quito | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png\",\"datePublished\":\"2018-12-24T00:53:48+00:00\",\"dateModified\":\"2018-12-24T00:56:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png\",\"width\":569,\"height\":309},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listo para la interconexi\u00f3n con el Metro de Quito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Listo para la interconexi\u00f3n con el Metro de Quito | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/","og_locale":"es_ES","og_type":"article","og_title":"Listo para la interconexi\u00f3n con el Metro de Quito | Mobilitas","og_description":"El gobierno de Quito destaca que el sistema de transporte metropolitano Troleb\u00fas, que cumple 23 a\u00f1os, est\u00e1 listo para su interconexi\u00f3n con el metro que se va a inaugurar el 2019. &nbsp;Durante las \u00faltimas dos d\u00e9cadas, el Trole, como es llamado, &nbsp;se consolid\u00f3 como un elemento fundamental para el desarrollo de la capital ecuatoriana y [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/","og_site_name":"Mobilitas","article_published_time":"2018-12-24T00:53:48+00:00","article_modified_time":"2018-12-24T00:56:38+00:00","og_image":[{"width":569,"height":309,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png","type":"image\/png"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"Listo para la interconexi\u00f3n con el Metro de Quito","datePublished":"2018-12-24T00:53:48+00:00","dateModified":"2018-12-24T00:56:38+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/"},"wordCount":465,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png","keywords":["destaque","TROLEBUS"],"articleSection":["Notas"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/","url":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/","name":"Listo para la interconexi\u00f3n con el Metro de Quito | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png","datePublished":"2018-12-24T00:53:48+00:00","dateModified":"2018-12-24T00:56:38+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-TROLEBUS-DE-QUITO.png","width":569,"height":309},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/23\/listo-para-la-interconexion-con-el-metro-de-quito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"Listo para la interconexi\u00f3n con el Metro de Quito"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=3625"}],"version-history":[{"count":3,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3625\/revisions"}],"predecessor-version":[{"id":3628,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3625\/revisions\/3628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/3629"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=3625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=3625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=3625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}