{"id":3180,"date":"2018-12-10T23:53:52","date_gmt":"2018-12-11T01:53:52","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=3180"},"modified":"2018-12-10T23:56:59","modified_gmt":"2018-12-11T01:56:59","slug":"tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/","title":{"rendered":"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX"},"content":{"rendered":"<p>Tres empresas de transporte p\u00fablico concesionado adquirieron 1,336 de los 3909 bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de la Ciudad de M\u00e9xico (Sedema) al mercado financiero. Un nota del gobierno de la Ciudad de M\u00e9xico informa que la iniciativa tiene el prop\u00f3sito de compensar sus emisiones de gases de efecto invernadero (GEI) generadas por estas empresas en sus operaciones.<\/p>\n<p>Dice la nota que las empresas concesionadas Vanguardia y Cambio, Conexi\u00f3n Centro Aeropuerto y Corredor Insurgentes adquirieron, en conjunto, el 34 % de los bonos. Los recursos obtenidos ser\u00e1n depositados en el Fondo Ambiental de Cambio Clim\u00e1tico para el financiamiento de acciones de conservaci\u00f3n y mantenimiento del Ejido de San Nicol\u00e1s Totolapan.<\/p>\n<p>En M\u00e9xico, \u2018ejido\u2019 es una sistem\u00e1tica de posesi\u00f3n y uso de la tierra por parte de una comunidad de personas, institucionalizada despu\u00e9s de la Revoluci\u00f3n Mexicana, y que est\u00e1 descripta en la Ley Agraria (26 de febrero 1992), que reglamenta el art\u00edculo 27 Constitucional en materia agraria.<\/p>\n<p>Por lo tanto, adem\u00e1s de promover el desarrollo con baja intensidad de carbono, como lo establece el <em>Programa de Acci\u00f3n Clim\u00e1tica de la Ciudad de M\u00e9xico 2014-2020<\/em>, las acciones buscan atender las necesidades de las comunidades rurales y fomentar la conservaci\u00f3n de los bosques.<\/p>\n<p><strong>EMISSIONES Y EL MECANISMO DE COMPENSACI\u00d3N<\/strong><\/p>\n<p>El transporte es el sector con mayor generaci\u00f3n de emisiones de gases (GEI), de acuerdo con el <em>Inventario de Emisiones 2016<\/em>, donde se muestra que los autobuses concesionados ocupan el segundo lugar en emisiones de bi\u00f3xido de carbono equivalente, con 563 mil toneladas de emisiones, mientras que los microbuses producen 880 mil toneladas.<\/p>\n<p>La nota se\u00f1ala la importancia de que este sector participe de manera activa en acciones que promuevan el desarrollo sustentable y buenas pr\u00e1cticas que pueden replicarse en las distintas rutas de transporte colectivo que operan en nuestra ciudad.<\/p>\n<p>La emisi\u00f3n de bonos de carbono forestal es un mecanismo financiero que ayuda a mitigar las emisiones de gases (GEI) causantes del cambio clim\u00e1tico. La Ciudad de M\u00e9xico es la primera entidad de Latinoam\u00e9rica en hacer uso de este instrumento, el cual fue registrado ante el Climate Action Reserve (CAR) del estado de California.<\/p>\n<p>Cada bono forestal equivale a 1,000 kg de carbono capturado de la atm\u00f3sfera, que se puede vender y comprar, y al mismo tiempo, mantener los \u00e1rboles que lo capturaron en pie. De enero de 2017 a agosto 2018, se lograron capturar en el bosque del Ejido, un total de 10 mil 235 toneladas de bi\u00f3xido de carbono, cantidad de emisiones equivalente a la que generan 3,239 autom\u00f3viles particulares durante un a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres empresas de transporte p\u00fablico concesionado adquirieron 1,336 de los 3909 bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de la Ciudad de M\u00e9xico (Sedema) al mercado financiero. Un nota del gobierno de la Ciudad de M\u00e9xico informa que la iniciativa tiene el prop\u00f3sito de compensar sus emisiones de gases de efecto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287,298],"tags":[686,683,684],"class_list":["post-3180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","category-radar-es","tag-bonos-forestales","tag-cdmx","tag-ejido-san-nicolas-totolapan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"Tres empresas de transporte p\u00fablico concesionado adquirieron 1,336 de los 3909 bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de la Ciudad de M\u00e9xico (Sedema) al mercado financiero. Un nota del gobierno de la Ciudad de M\u00e9xico informa que la iniciativa tiene el prop\u00f3sito de compensar sus emisiones de gases de efecto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-11T01:53:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-11T01:56:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"621\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX\",\"datePublished\":\"2018-12-11T01:53:52+00:00\",\"dateModified\":\"2018-12-11T01:56:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png\",\"keywords\":[\"BONOS FORESTALES\",\"CDMX\",\"EJIDO SAN NICOL\u00c1S TOTOLAP\u00c1N\"],\"articleSection\":[\"Notas\",\"Radar\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\",\"name\":\"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png\",\"datePublished\":\"2018-12-11T01:53:52+00:00\",\"dateModified\":\"2018-12-11T01:56:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png\",\"width\":621,\"height\":368,\"caption\":\"Autobuses en la CDMX. Foto: CISA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/","og_locale":"es_ES","og_type":"article","og_title":"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX | Mobilitas","og_description":"Tres empresas de transporte p\u00fablico concesionado adquirieron 1,336 de los 3909 bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de la Ciudad de M\u00e9xico (Sedema) al mercado financiero. Un nota del gobierno de la Ciudad de M\u00e9xico informa que la iniciativa tiene el prop\u00f3sito de compensar sus emisiones de gases de efecto [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/","og_site_name":"Mobilitas","article_published_time":"2018-12-11T01:53:52+00:00","article_modified_time":"2018-12-11T01:56:59+00:00","og_image":[{"width":621,"height":368,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png","type":"image\/png"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX","datePublished":"2018-12-11T01:53:52+00:00","dateModified":"2018-12-11T01:56:59+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/"},"wordCount":472,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png","keywords":["BONOS FORESTALES","CDMX","EJIDO SAN NICOL\u00c1S TOTOLAP\u00c1N"],"articleSection":["Notas","Radar"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/","url":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/","name":"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png","datePublished":"2018-12-11T01:53:52+00:00","dateModified":"2018-12-11T01:56:59+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-AUTOBUSES-2-CORTADA-EMBAIXO.png","width":621,"height":368,"caption":"Autobuses en la CDMX. Foto: CISA"},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/10\/tres-empresas-concesionadas-de-transporte-publico-compraron-el-34-de-los-bonos-de-carbono-forestal-que-lanzo-la-secretaria-del-medio-ambiente-de-cdmx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"Tres empresas concesionadas de transporte p\u00fablico compraron el 34% de los bonos de carbono forestal que lanz\u00f3 la Secretar\u00eda del Medio Ambiente de CDMX"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=3180"}],"version-history":[{"count":1,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3180\/revisions"}],"predecessor-version":[{"id":3183,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3180\/revisions\/3183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/3186"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=3180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=3180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=3180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}