{"id":3127,"date":"2018-12-04T18:28:16","date_gmt":"2018-12-04T20:28:16","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=3127"},"modified":"2018-12-04T18:28:16","modified_gmt":"2018-12-04T20:28:16","slug":"la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/","title":{"rendered":"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico"},"content":{"rendered":"<p>Pensar los espacios p\u00fablicos desde las necesidades de las mujeres y velar por su seguridad p\u00fablica y privada \u2013 aspectos que se refieren a la situaci\u00f3n femenina en las calles y en los medios de transporte p\u00fablico \u2013 son dos de los puntos que sobresalenen la declaraci\u00f3n final del <em>Encuentro Nacional de Alcaldesas y Concejalas<\/em>de Chile, realizado en la ciudad de Vi\u00f1a del Mar los d\u00edas 28, 29 y 30 de noviembre de 2018, y que cont\u00f3 con la presencia de m\u00e1s de 150 representantes de municipios de todo el pa\u00eds. La informaci\u00f3n fue divulgada por el sitio de la Asociaci\u00f3n Chilena de Municipalidades (AChM).<\/p>\n<p>Los temas tratados en el encuentro fueron: Realidad pol\u00edtica y social de la mujer en Am\u00e9rica Latina, An\u00e1lisis y situaci\u00f3n actual de los pueblos originarios en el contexto de la equidad de g\u00e9nero, Proyecci\u00f3n y perspectivas en la integraci\u00f3n de los pueblos originarios en el marco de la equidad de g\u00e9nero, Las brechas de g\u00e9nero en el espacio pol\u00edtico local, El estado y las pol\u00edticas de equidad de g\u00e9nero, Los municipios como impulsores de los planes y programas. Y una pregunta:\u00a0 \u00bfLa legislaci\u00f3n actual responde a la equidad de g\u00e9nero? La nota completa, con todos los puntos de la declaraci\u00f3n final del <em>Encuentro Nacional de Alcaldesas y Concejalas<\/em> <em>de Chile<\/em> se puede ver <a href=\"https:\/\/www.achm.cl\/index.php\/noticias\/item\/1163-principales-acuerdos-y-conclusiones-encuentro-de-alcaldesas-y-concejalas\" target=\"_blank\" rel=\"noopener\"><strong>aqu\u00ed<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pensar los espacios p\u00fablicos desde las necesidades de las mujeres y velar por su seguridad p\u00fablica y privada \u2013 aspectos que se refieren a la situaci\u00f3n femenina en las calles y en los medios de transporte p\u00fablico \u2013 son dos de los puntos que sobresalenen la declaraci\u00f3n final del Encuentro Nacional de Alcaldesas y Concejalasde [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287,298],"tags":[670,671,672],"class_list":["post-3127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","category-radar-es","tag-asociacion-chilena-de-municipalidades","tag-encontro-nacional-de-alcadezas-y-consejalas-de-chile","tag-vina-del-mar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"Pensar los espacios p\u00fablicos desde las necesidades de las mujeres y velar por su seguridad p\u00fablica y privada \u2013 aspectos que se refieren a la situaci\u00f3n femenina en las calles y en los medios de transporte p\u00fablico \u2013 son dos de los puntos que sobresalenen la declaraci\u00f3n final del Encuentro Nacional de Alcaldesas y Concejalasde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-04T20:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"571\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico\",\"datePublished\":\"2018-12-04T20:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\"},\"wordCount\":265,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png\",\"keywords\":[\"ASOCIACION CHILENA DE MUNICIPALIDADES\",\"ENCONTRO NACIONAL DE ALCADEZAS Y CONSEJALAS DE CHILE\",\"VI\u00d1A DEL MAR\"],\"articleSection\":[\"Notas\",\"Radar\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\",\"name\":\"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png\",\"datePublished\":\"2018-12-04T20:28:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png\",\"width\":571,\"height\":341,\"caption\":\"Participantes del encuentro. Foto: AChM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/","og_locale":"es_ES","og_type":"article","og_title":"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico | Mobilitas","og_description":"Pensar los espacios p\u00fablicos desde las necesidades de las mujeres y velar por su seguridad p\u00fablica y privada \u2013 aspectos que se refieren a la situaci\u00f3n femenina en las calles y en los medios de transporte p\u00fablico \u2013 son dos de los puntos que sobresalenen la declaraci\u00f3n final del Encuentro Nacional de Alcaldesas y Concejalasde [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/","og_site_name":"Mobilitas","article_published_time":"2018-12-04T20:28:16+00:00","og_image":[{"width":571,"height":341,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png","type":"image\/png"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico","datePublished":"2018-12-04T20:28:16+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/"},"wordCount":265,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png","keywords":["ASOCIACION CHILENA DE MUNICIPALIDADES","ENCONTRO NACIONAL DE ALCADEZAS Y CONSEJALAS DE CHILE","VI\u00d1A DEL MAR"],"articleSection":["Notas","Radar"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/","url":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/","name":"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png","datePublished":"2018-12-04T20:28:16+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/12\/MOBILITAS-ALCADEZAS-E-CONSEJALAS.png","width":571,"height":341,"caption":"Participantes del encuentro. Foto: AChM"},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2018\/12\/04\/la-declaracion-del-encuentro-nacional-de-alcaldesas-y-concejalas-de-chile-tiene-puntos-sobre-la-inseguridad-femenina-en-las-calles-y-en-el-transporte-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"La declaraci\u00f3n del Encuentro Nacional de Alcaldesas y Concejalas de Chile tiene puntos sobre la inseguridad femenina en las calles y en el transporte p\u00fablico"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=3127"}],"version-history":[{"count":1,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3127\/revisions"}],"predecessor-version":[{"id":3130,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/3127\/revisions\/3130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/3128"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=3127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=3127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=3127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}