{"id":2948,"date":"2018-11-15T16:37:37","date_gmt":"2018-11-15T18:37:37","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=2948"},"modified":"2018-11-15T17:16:10","modified_gmt":"2018-11-15T19:16:10","slug":"la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/","title":{"rendered":"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019"},"content":{"rendered":"<p>En una reuni\u00f3n el 15 de noviembre de 2018 con el vicepresidente electo de Brasil, general Ant\u00f4nio Hamilton Martins Mour\u00e3o, dirigentes de la Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles (ANPTrilhos), entregaron al futuro gobierno el documento <em>Propuestas para el Avance de la Movilidad Urbana Nacional<\/em>.<\/p>\n<p>El texto indica cinco temas prioritarios para la reflexi\u00f3n, relacionados con la movilidad urbana nacional. Los temas se basan en un nuevo enfoque de inversi\u00f3n gubernamental, prioritario en sistemas sobre rieles como espina dorsal de una amplia red de transporte integrada con otros modales.<\/p>\n<p>Los temas son los siguientes: 1) Elaboraci\u00f3n de un amplio Plan de Estructura Estrat\u00e9gica de la Movilidad Urbana Nacional, con foco en el transporte de pasajeros sobre rieles; 2) Prioridades de inversiones en el Plan de Movilidad Urbana Nacional; 3) Fortalecer marcos regulatorios &#8211; Seguridad Jur\u00eddica; 4) Incentivo para la modernizaci\u00f3n y ampliaci\u00f3n de los sistemas de transporte de pasajeros sobre ra\u00edles; 5) Instituci\u00f3n de tasas de financiaci\u00f3n m\u00e1s atractivas para proyectos estructurantes de transporte de pasajeros sostenible.<\/p>\n<p>La apertura del documento subraya: &#8220;La adopci\u00f3n de las cinco medidas ser\u00e1 capaz de ofrecer a la Naci\u00f3n brasile\u00f1a, en poco tiempo, una verdadera infraestructura estrat\u00e9gica de movilidad nacional, conectando todas las medianas y grandes ciudades y tambi\u00e9n las regiones metropolitanas. , abrir\u00e1 el camino para que las peque\u00f1as ciudades puedan, efectivamente, interconectar sus redes de transporte con ese mismo enfoque de eficiencia y regularidad &#8211; una de las principales caracter\u00edsticas del transporte de pasajeros sobre rieles\u201d.<\/p>\n<p><a href=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/181115-DOCUMENTO-ANPTRILHOS-NOVO-GOVERNO.pdf\" target=\"_blank\" rel=\"noopener\"><em><strong>Ver el documento (en portugu\u00e9s)<\/strong><\/em><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una reuni\u00f3n el 15 de noviembre de 2018 con el vicepresidente electo de Brasil, general Ant\u00f4nio Hamilton Martins Mour\u00e3o, dirigentes de la Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles (ANPTrilhos), entregaron al futuro gobierno el documento Propuestas para el Avance de la Movilidad Urbana Nacional. El texto indica cinco temas prioritarios para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287],"tags":[615,323,471,614],"class_list":["post-2948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","tag-anpetrilhos-es","tag-brasil-es","tag-en-foco","tag-transporte-de-pasajeros-osbre-rieles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019 | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019 | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"En una reuni\u00f3n el 15 de noviembre de 2018 con el vicepresidente electo de Brasil, general Ant\u00f4nio Hamilton Martins Mour\u00e3o, dirigentes de la Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles (ANPTrilhos), entregaron al futuro gobierno el documento Propuestas para el Avance de la Movilidad Urbana Nacional. El texto indica cinco temas prioritarios para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-15T18:37:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-15T19:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019\",\"datePublished\":\"2018-11-15T18:37:37+00:00\",\"dateModified\":\"2018-11-15T19:16:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\"},\"wordCount\":295,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png\",\"keywords\":[\"ANPETRILHOS\",\"BRASIL\",\"En Foco\",\"TRANSPORTE DE PASAJEROS OSBRE RIELES\"],\"articleSection\":[\"Notas\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\",\"name\":\"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019 | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png\",\"datePublished\":\"2018-11-15T18:37:37+00:00\",\"dateModified\":\"2018-11-15T19:16:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png\",\"width\":505,\"height\":301,\"caption\":\"Esta\u00e7\u00e3o Higien\u00f3polis-Mackenzie, Linha 4, S\u00e3o Paulo. Foto: Alexandre Carvalho A2IMG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019 | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/","og_locale":"es_ES","og_type":"article","og_title":"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019 | Mobilitas","og_description":"En una reuni\u00f3n el 15 de noviembre de 2018 con el vicepresidente electo de Brasil, general Ant\u00f4nio Hamilton Martins Mour\u00e3o, dirigentes de la Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles (ANPTrilhos), entregaron al futuro gobierno el documento Propuestas para el Avance de la Movilidad Urbana Nacional. El texto indica cinco temas prioritarios para [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/","og_site_name":"Mobilitas","article_published_time":"2018-11-15T18:37:37+00:00","article_modified_time":"2018-11-15T19:16:10+00:00","og_image":[{"width":505,"height":301,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png","type":"image\/png"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019","datePublished":"2018-11-15T18:37:37+00:00","dateModified":"2018-11-15T19:16:10+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/"},"wordCount":295,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png","keywords":["ANPETRILHOS","BRASIL","En Foco","TRANSPORTE DE PASAJEROS OSBRE RIELES"],"articleSection":["Notas"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/","url":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/","name":"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019 | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png","datePublished":"2018-11-15T18:37:37+00:00","dateModified":"2018-11-15T19:16:10+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/11\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-6-ALEXANDRE-CARVALHO-A2-IMG.png","width":505,"height":301,"caption":"Esta\u00e7\u00e3o Higien\u00f3polis-Mackenzie, Linha 4, S\u00e3o Paulo. Foto: Alexandre Carvalho A2IMG"},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2018\/11\/15\/la-asociacion-nacional-de-los-transportistas-de-pasajeros-sobre-rieleros-anptrilhos-de-brasil-entrega-al-futuro-gobierno-el-documento-propuestas-para-el-avance-de-la-movilidad-urbana-naci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"La Asociaci\u00f3n Nacional de los Transportistas de Pasajeros sobre Rieles, de Brasil, entrega al futuro gobierno el documento \u2018Propuestas para el Avance de la Movilidad Urbana Nacional\u2019"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=2948"}],"version-history":[{"count":3,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2948\/revisions"}],"predecessor-version":[{"id":2955,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2948\/revisions\/2955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/2962"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=2948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=2948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=2948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}