{"id":2743,"date":"2018-10-26T18:49:33","date_gmt":"2018-10-26T21:49:33","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=2743"},"modified":"2018-10-27T00:34:40","modified_gmt":"2018-10-27T03:34:40","slug":"open-house-buenos-aires","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/","title":{"rendered":"Open House Buenos Aires"},"content":{"rendered":"<p><strong><em>La iniciativa consiste en un fin de semana al a\u00f1o que la ciudad abre las puertas de sus edificios para que puedan ser visitados por un p\u00fablico general. Son edificios seleccionados por su valor arquitect\u00f3nico, patrimonial y cultural a los que habitualmente no se puede ingresar libremente.\u00a0 <\/em><\/strong><\/p>\n<p>En este fin de semana, el 27 y 28 de octubre de 2018, se realiza el evento <em>Open House Buenos Aires<\/em>, un festival de arquitectura y urbanismo. Se trata de dos d\u00edas de puertas abiertas de 112 edificios que producen admiraci\u00f3n y curiosidad. El festival ofrece la oportunidad de ingresar y recorrer en forma gratuita aquellos lugares privados o p\u00fablicos que normalmente se encuentran cerrados al p\u00fablico general.<\/p>\n<p>Buenos Aires fue la primera ciudad de Latinoam\u00e9rica en adoptar el concepto <em>Open House<\/em>. El festival est\u00e1 dirigido a todo aquel que est\u00e9 interesado en redescubrir la arquitectura y el urbanismo de la ciudad de Buenos Aires. Pone a disposici\u00f3n una serie de interiores privados de valor arquitect\u00f3nico, cultural y patrimonial \u2013 que por lo general est\u00e1n cerrados al p\u00fablico\u2013 para ser visitados con la colaboraci\u00f3n de voluntarios que ofrecen su tiempo para acompa\u00f1ar y comentar las recorridas.<\/p>\n<p><strong>LOS ORGANIZADORES<\/strong><\/p>\n<p>El festival es organizado por CoHabitarUrbano, una asociaci\u00f3n civil sin fines de lucro creada con el prop\u00f3sito de fomentar el v\u00ednculo creativo entre la ciudad y su gente.<\/p>\n<p>En el sitio del evento, la Asociaci\u00f3n afirma: \u201cPropiciamos una mirada cr\u00edtica hacia el medio ambiente construido agudizando la percepci\u00f3n de las personas de sus ciudades. Creemos que as\u00ed nos convertimos en verdaderos ciudadanos capaces de exigir lugares de calidad para el desarrollo de la vida en la ciudad. Somos un equipo multidisciplinario que mira y act\u00faa desde y para la ciudad a partir de distintos puntos de vista intentando captar las m\u00faltiples sensibilidades de quienes cohabitamos la ciudad de Buenos Aires\u201d.<\/p>\n<p>Los organizadores se\u00f1alan\u00a0 aun que 685 voluntarios \u201cgenerosamente ofrecen su tiempo y su entusiasmo para permitirnos a todos recorrer esos lugares que nos producen admiraci\u00f3n y curiosidad\u201d.<\/p>\n<p><strong>PARTICIPACI\u00d3N MINISTERIAL<\/strong><\/p>\n<p>El Ministerio de Desarrollo Urbano y Transporte inform\u00f3 que participar\u00e1 este fin de semana del <em>Open House Buenos Aires<\/em>: los vecinos podr\u00e1n visitar en forma gratuita y conocer el Palacio Lezama, la nueva traza de la L\u00ednea E y el Centro de Trasbordo Constituci\u00f3n.<\/p>\n<p>El Palacio Lezama, ubicado en el barrio de La Boca, en la avenida Mart\u00edn Garc\u00eda 346, se podr\u00e1 visitar el s\u00e1bado 27 de octubre entre las 10 y las 13, previa inscripci\u00f3n en la web de Open House. En la actualidad aloja las oficinas del Ministerio de Desarrollo Urbano y Transporte y el de Ambiente y de Espacio P\u00fablico. All\u00ed, hasta el a\u00f1o 2000, se fabricaron los famosos bizcochos Canale, una tradici\u00f3n argentina. La fachada conserva el estilo industrial de su \u00e9poca.<\/p>\n<p>Ese mismo s\u00e1bado entre las 11 y las 13, pero en Retiro, los vecinos podr\u00e1n conocer 2 de las 3 estaciones de la L\u00ednea E que se inaugurar\u00e1n en mayo de 2019. Adem\u00e1s, los inscriptos en la web podr\u00e1n caminar por el t\u00fanel y visitar las nuevas instalaciones del Subte.<\/p>\n<p>Mientras que el domingo 28 a las 15, los vecinos de la Ciudad podr\u00e1n recorrer el Centro de Trasbordo Constituci\u00f3n, sin inscripci\u00f3n previa. Ubicado en la Comuna 1, es una obra que permite la mejor conexi\u00f3n de la cabecera de la l\u00ednea Roca de trenes, la L\u00ednea C de Subtes y 34 l\u00edneas de colectivos. Durante la visita, los asistentes podr\u00e1n escuchar la charla a cargo del estudio Vila Sebasti\u00e1n Arquitectos, responsables del desarrollo del proyecto y de la direcci\u00f3n de obra entre 2014 y 2015.<\/p>\n<p><a href=\"http:\/\/www.openhousebsas.org\/index\/nosotros\" target=\"_blank\" rel=\"noopener\"><strong><em>Vea otras informaciones en el sitio web del Open House Buenos Aires<\/em><\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa consiste en un fin de semana al a\u00f1o que la ciudad abre las puertas de sus edificios para que puedan ser visitados por un p\u00fablico general. Son edificios seleccionados por su valor arquitect\u00f3nico, patrimonial y cultural a los que habitualmente no se puede ingresar libremente.\u00a0 En este fin de semana, el 27 y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287],"tags":[313,562,315,565,80],"class_list":["post-2743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","tag-argentina-es","tag-arquitectura","tag-buenos-aires-es","tag-ministerio-de-desarrollo-urbano-y-transporte-de-argentina","tag-urbanismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Open House Buenos Aires | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open House Buenos Aires | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"La iniciativa consiste en un fin de semana al a\u00f1o que la ciudad abre las puertas de sus edificios para que puedan ser visitados por un p\u00fablico general. Son edificios seleccionados por su valor arquitect\u00f3nico, patrimonial y cultural a los que habitualmente no se puede ingresar libremente.\u00a0 En este fin de semana, el 27 y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-26T21:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-27T03:34:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"592\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"Open House Buenos Aires\",\"datePublished\":\"2018-10-26T21:49:33+00:00\",\"dateModified\":\"2018-10-27T03:34:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\"},\"wordCount\":643,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg\",\"keywords\":[\"ARGENTINA\",\"ARQUITECTURA\",\"BUENOS AIRES\",\"Ministerio de Desarrollo Urbano y Transporte de Argentina\",\"Urbanismo\"],\"articleSection\":[\"Notas\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\",\"name\":\"Open House Buenos Aires | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg\",\"datePublished\":\"2018-10-26T21:49:33+00:00\",\"dateModified\":\"2018-10-27T03:34:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg\",\"width\":592,\"height\":314,\"caption\":\"Foto reproducida del sitio Open House Buenos Aires\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Open House Buenos Aires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Open House Buenos Aires | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/","og_locale":"es_ES","og_type":"article","og_title":"Open House Buenos Aires | Mobilitas","og_description":"La iniciativa consiste en un fin de semana al a\u00f1o que la ciudad abre las puertas de sus edificios para que puedan ser visitados por un p\u00fablico general. Son edificios seleccionados por su valor arquitect\u00f3nico, patrimonial y cultural a los que habitualmente no se puede ingresar libremente.\u00a0 En este fin de semana, el 27 y [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/","og_site_name":"Mobilitas","article_published_time":"2018-10-26T21:49:33+00:00","article_modified_time":"2018-10-27T03:34:40+00:00","og_image":[{"width":592,"height":314,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg","type":"image\/jpeg"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"Open House Buenos Aires","datePublished":"2018-10-26T21:49:33+00:00","dateModified":"2018-10-27T03:34:40+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/"},"wordCount":643,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg","keywords":["ARGENTINA","ARQUITECTURA","BUENOS AIRES","Ministerio de Desarrollo Urbano y Transporte de Argentina","Urbanismo"],"articleSection":["Notas"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/","url":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/","name":"Open House Buenos Aires | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg","datePublished":"2018-10-26T21:49:33+00:00","dateModified":"2018-10-27T03:34:40+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS6OPENHOUSEBUENOSAIRES-CORTADA-2.jpg","width":592,"height":314,"caption":"Foto reproducida del sitio Open House Buenos Aires"},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/26\/open-house-buenos-aires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"Open House Buenos Aires"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=2743"}],"version-history":[{"count":5,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2743\/revisions"}],"predecessor-version":[{"id":2760,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2743\/revisions\/2760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/2756"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=2743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=2743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=2743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}