{"id":2491,"date":"2018-10-01T13:35:10","date_gmt":"2018-10-01T16:35:10","guid":{"rendered":"https:\/\/mobilitas.lat\/?p=2491"},"modified":"2018-10-01T14:19:28","modified_gmt":"2018-10-01T17:19:28","slug":"mais-de-cem-quilometros","status":"publish","type":"post","link":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/","title":{"rendered":"M\u00e1s de cien kil\u00f3metros"},"content":{"rendered":"<p><strong><em>Sistema de metro de la ciudad de San Pablo debe terminar 2018 con m\u00e1s de cien kil\u00f3metros.\u00a0En 2010, la red de metro era de 68,9 kil\u00f3metros, alcanz\u00f3 los 77,4 kil\u00f3metros en 2015 y lleg\u00f3 a 80,4 kil\u00f3metros en agosto de 2018. La ciudad conta aun com 140 kil\u00f3metros del sistema de trenes metropolitanos.<\/em><\/strong><\/p>\n<div id=\"attachment_2488\" style=\"width: 383px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2488\" class=\"wp-image-2487 \" src=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-PELISSIONI-CONFERENCIA-FINAL-24-SEMANA-AEAMESP.png\" alt=\"\" width=\"373\" height=\"235\" srcset=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-PELISSIONI-CONFERENCIA-FINAL-24-SEMANA-AEAMESP.png 251w, https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-PELISSIONI-CONFERENCIA-FINAL-24-SEMANA-AEAMESP-240x152.png 240w, https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-PELISSIONI-CONFERENCIA-FINAL-24-SEMANA-AEAMESP-205x130.png 205w\" sizes=\"auto, (max-width: 373px) 100vw, 373px\" \/><p id=\"caption-attachment-2488\" class=\"wp-caption-text\">Clodoaldo Pelissioni<\/p><\/div>\n<p>En operaci\u00f3n hace 44 a\u00f1os &#8211; las actividades empezaron el 14 de septiembre de 1974 &#8211; el sistema de metro de la ciudad de San Pablo deber\u00e1 terminar el 2018 con m\u00e1s de cien kil\u00f3metros de l\u00edneas, seg\u00fan asegur\u00f3 el secretario de Transportes Metropolitanos del Estado de San Pablo, Clodoaldo Pelissioni, en la conferencia de clausura de la <em>24\u00aa Semana de Tecnolog\u00eda Metro-ferroviaria<\/em>, promovida por la Asociaci\u00f3n de Ingenieros y Arquitectos de Metro (AEAMESP), considerado el evento t\u00e9cnico m\u00e1s expresivo del sector metro-vial en Brasil.<\/p>\n<p>Pelissioni hizo un balance r\u00e1pido de las inversiones en esta d\u00e9cada y dej\u00f3 como elemento de reflexi\u00f3n un conjunto de cinco temas del \u00e1rea de movilidad urbana que tendr\u00e1n que enfrentar los futuros gobiernos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2495\" src=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/AEAMESP-FOTOS-METR\u00d4-SP-300x201.png\" alt=\"\" width=\"384\" height=\"257\" srcset=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/AEAMESP-FOTOS-METR\u00d4-SP-300x201.png 300w, https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/AEAMESP-FOTOS-METR\u00d4-SP.png 571w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/>El secretario afirm\u00f3 inicialmente que en San Pablo, en 2010, la red de metro era de 68,9 kil\u00f3metros, alcanz\u00f3 los 77,4 kil\u00f3metros en 2015 y lleg\u00f3 a 80,4 kil\u00f3metros en agosto de 2018. &#8220;Hasta fines del 2018 llegaremos a los 102 kil\u00f3metros, con las inauguraciones de la L\u00ednea 5 \u2013 Lila (a principios de octubre, faltaba apenas una estaci\u00f3n a ser inaugurada), de la L\u00ednea 15\u00a0 &#8211; Plata y de la L\u00ednea 4 &#8211; Amarilla. Y hay planes para que, con la L\u00ednea 6 &#8211; Naranja y la L\u00ednea 17 \u2013 Oro, se pueda llegar a 129 kil\u00f3metros hasta 2022.&#8221;<\/p>\n<p>En cuanto a las estaciones del sistema metro-vial, dijo que en 2010 eran 60; en 2015, 68 y en 2017, 71. &#8220;En agosto de 2018, son 79 estaciones y vamos a llegar a 89 hasta fines de 2018. Tenemos la previsi\u00f3n de m\u00e1s de diez estaciones: cinco en la L\u00ednea 5 &#8211; Lila, cuatro en el monoriel de la L\u00ednea 15 &#8211; Plata y una m\u00e1s en la L\u00ednea 4 &#8211; Amarilla. Y se prev\u00e9n 25 estaciones m\u00e1s para el pr\u00f3ximo cuadrienio.<\/p>\n<p>Sobre la Compa\u00f1\u00eda Paulista de Trenes Metropolitanos (CPTM), dijo que se agregaron 12 kil\u00f3metros a la red con la L\u00ednea 13 &#8211; Jade, que hace conexi\u00f3n con el aeropuerto internacional de Guarulhos (Cumbica), lo que le agreg\u00f3 dos estaciones m\u00e1s al sistema. Heredera de l\u00edneas antiguas implantadas entre los a\u00f1os 1860 y 1930, la CPTM, creada en 1992, posee una red de 267 kil\u00f3metros, que atiende a 22 municipios de la Regi\u00f3n Metropolitana de San Pablo; cerca de 140 kil\u00f3metros est\u00e1n dentro de la ciudad de San Pablo. Se trata de una malla que se viene modernizando tecnol\u00f3gicamente y que est\u00e1 integrada f\u00edsica y tarifariamente a la red de metro.<\/p>\n<p>Al respecto de la Empresa Metropolitana de Transportes Urbanos (EMTU), mostr\u00f3 que actualmente, est\u00e1n operando 11,4 kil\u00f3metros del sistema de Veh\u00edculo Ligero sobre Rieles (VLT) de la <em>Baixada Santista<\/em> y que con la segunda etapa de la licitaci\u00f3n, habr\u00e1 una ampliaci\u00f3n considerable del servicio: &#8220;Tenemos 15 estaciones y pasaremos a 29 estaciones&#8221;. Tambi\u00e9n coment\u00f3 que en 2010 hab\u00eda 64 kil\u00f3metros de corredores de \u00f3mnibus y a fines del 2018 ser\u00e1n 95 kil\u00f3metros de este tipo de transporte.<\/p>\n<p>Con relaci\u00f3n a los trenes, inform\u00f3 que en los sistemas sobre rieles metropolitanos de San Pablo a fines del 2018 habr\u00e1 un total de 191 trenes nuevos o modernizados. &#8220;Si sacamos los 36 modernizados, vamos a tener 155 trenes nuevos, contemplando la L\u00ednea 4 &#8211; Amarilla, la L\u00ednea 5 &#8211; Lila, la L\u00ednea 15 &#8211; Plata en monoriel y el sistema VLT en la <em>Baixada Santista<\/em>, adem\u00e1s de 65 trenes nuevos en la CPTM. Son composiciones con seis, siete u ocho vagones, lo que totaliza 1023 vagones nuevos en el sistema. La modernizaci\u00f3n en el Metro, que la terminaremos a fines del 2018, implic\u00f3 98 trenes.<\/p>\n<p>El secretario tambi\u00e9n present\u00f3 n\u00fameros referentes a la estaciones ya acordes con las normas de accesibilidad universal. &#8220;En el Metro -SP, todas las estaciones son accesibles. En la CPTM, llegaremos a fin de a\u00f1o con 71 y dejaremos proyectos y obras para que todas las estaciones puedan ser accesibles hasta fines del 2022.<\/p>\n<p>Sobre el total de pasajeros transportados en los sistemas, afirm\u00f3 que en 2017 se hab\u00edan contabilizado un promedio de 7,1 millones por d\u00eda. &#8220;Estamos llegando a 7,5 millones ahora y se alcanzan los 7,7 millones en d\u00edas de mucho movimiento. Hasta fines del 2018 pretendemos llegar a m\u00e1s de 8,5 millones de pasajeros transportados por d\u00eda. En la EMTU, tenemos 2,2 millones transportados todos los d\u00edas en los autobuses.<\/p>\n<p>El secretario tambi\u00e9n mostr\u00f3 los n\u00fameros referentes a las inversiones. En 2015, se invirtieron R$ 4,8 mil millones (USD 1,185 mil millones); en 2016, R$ 4,29 mil millones (USD 1,059 mil millones); en 2017, R$ 4,24 mil millones (USD 1,046 mil millones) y R$ 4,18 mil millones m\u00e1s (USD 1,032 mil millones) en 2018. &#8220;Al final de este a\u00f1o llegaremos a R$ 17,6 mil millones (USD 4,345 mil millones) de inversiones en el presente cuadrienio.<\/p>\n<p><strong>CRONOGRAMA<\/strong><\/p>\n<p>Al responder las preguntas del p\u00fablico presente, Clodoaldo Pelissioni actualiz\u00f3 el cronograma de inauguraciones. En cuanto a la L\u00ednea 5 &#8211; Lila, dijo que se entregar\u00eda una estaci\u00f3n m\u00e1s en agosto de 2018 y que las otras cuatro se inaugurar\u00edan hasta diciembre del 2018.<\/p>\n<p>La inauguraci\u00f3n de la estaci\u00f3n S\u00e3o Paulo-Morumbi de la L\u00ednea 4 &#8211; Amarilla ser\u00e1 en octubre. Mientras que para la l\u00ednea 15 &#8211; Plata, en monorieles, estaba prevista la inauguraci\u00f3n de una estaci\u00f3n entre septiembre y octubre y hasta fin de a\u00f1o la entrega de las otras tres.<\/p>\n<p>Sobre la L\u00ednea 6 &#8211; Naranja, afirm\u00f3 que cree que la Justicia debe autorizar la rescisi\u00f3n del contrato con el consorcio vencedor y que posteriormente se mostr\u00f3 incapaz de continuar las obras. Espera que se retome el proceso de licitaci\u00f3n de esta l\u00ednea a\u00fan en 2018.<\/p>\n<p>Seg\u00fan Pelissioni, en septiembre de 2018 deber\u00e1 publicarse el pliego para la contrataci\u00f3n de puertas-plataforma para 36 estaciones de la L\u00ednea 1 &#8211; Azul, de la L\u00ednea 2 &#8211; Verde y de la L\u00ednea 3 &#8211; Roja. La ejecuci\u00f3n de este servicio est\u00e1 prevista para 2019.<\/p>\n<p>Con relaci\u00f3n al Tren Interciudades, para interconectar San Pablo, Jundia\u00ed, Campinas y Americana (una regi\u00f3n paulista muy industrializada), Pelissioni coment\u00f3 que el proyecto avanz\u00f3 pero que se depara con el tema de la falta de recursos. &#8220;Es un proyecto de R$ 5,4 mil millones (USD 1,333 mil millones) de los cuales la iniciativa privada deber\u00e1 bancar dos tercios y el resto vendr\u00e1 de aportes del estado&#8221;, afirm\u00f3. El estudio de viabilidad ya se produjo y el gobierno del estado de San Pablo lo est\u00e1 analizando. El objetivo del estudio, que se est\u00e1 &#8220;refinando&#8221; seg\u00fan el gobierno, es recopilar informaciones sobre la ruta inicial del tren, que recorrer\u00e1 135 kil\u00f3metros.<\/p>\n<p><strong>CUESTIONES QUE HAY QUE ENFRENTAR<\/strong><\/p>\n<p>Sobre el futuro inmediato, Clodoaldo Pelissioni afirm\u00f3. &#8220;En Brasil, tenemos 27 regiones con m\u00e1s de un mill\u00f3n de habitantes, consideradas regiones metropolitanas. S\u00f3lo aqu\u00ed en el estado de San Pablo, son siete. La mitad de la poblaci\u00f3n brasile\u00f1a vive en estas regiones metropolitanas. Entonces, nuestro desaf\u00edo es: garantizar que haya recursos para invertir en movilidad en estas regiones y realizar los emprendimientos con eficiencia, es decir, empezar de la forma correcta y terminar de la forma correcta&#8221;. Para tanto, present\u00f3 un conjunto de cinco &#8220;batallas&#8221; que los futuros gobiernos deber\u00e1n enfrentar.<\/p>\n<p>La primera es el ajuste fiscal, para que pueda haber recursos p\u00fablicos para inversiones, lo que actualmente no sucede. Record\u00f3 que mientras que en econom\u00edas como la de China y la de Corea del Sur invierten m\u00e1s del 10% de PIB por a\u00f1o, en Brasil, seg\u00fan el peri\u00f3dico O Estado de S. Paulo, la inversi\u00f3n en 2019 ser\u00e1 del 0,3% del PIB.<\/p>\n<p>La segunda batalla por librar es la b\u00fasqueda de la mejora en las reglas y las leyes de la licitaci\u00f3n y de los an\u00e1lisis del tribunal de cuentas, de modo que, sin perder la eficiencia del control, sean m\u00e1s \u00e1giles en los procesos.<\/p>\n<p>La mejora de calidad de los proyectos para que las concesiones de las alianzas p\u00fablico privadas (APP) fue el tercer punto a enfrentar que mencion\u00f3 el secretario. &#8220;Necesitamos tener proyectos funcionales realistas y con flujos de demanda minuciosos&#8221;.<\/p>\n<p>El secretario se\u00f1al\u00f3 como el cuarto aspecto la necesidad de simplificaci\u00f3n y desburocratizaci\u00f3n de las financiaciones, de modo que se puedan tomar en un tiempo razonable.<\/p>\n<p>La quinta batalla es la necesidad de traer hacia dentro del emprendimiento la valorizaci\u00f3n inmobiliaria; la idea es establecer mecanismos para que la implantaci\u00f3n de los sistemas p\u00fablicos en el \u00e1rea de movilidad urbana se puedan financiar con emprendimientos inmobiliarios o por la captura de la valorizaci\u00f3n que naturalmente causan los inmuebles de los alrededores.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_2497\" style=\"width: 613px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2497\" class=\" wp-image-2496\" src=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIENOPOLIS-MACKENZIE-1-ALEXANDRE-CARVALHO-A2-IMG-300x207.png\" alt=\"\" width=\"603\" height=\"418\" \/><p id=\"caption-attachment-2497\" class=\"wp-caption-text\">Metr\u00f4 de S\u00e3o Paulo. Foto: Alexandre Carvalho A2 IMG<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sistema de metro de la ciudad de San Pablo debe terminar 2018 con m\u00e1s de cien kil\u00f3metros.\u00a0En 2010, la red de metro era de 68,9 kil\u00f3metros, alcanz\u00f3 los 77,4 kil\u00f3metros en 2015 y lleg\u00f3 a 80,4 kil\u00f3metros en agosto de 2018. La ciudad conta aun com 140 kil\u00f3metros del sistema de trenes metropolitanos. En operaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[287],"tags":[504,505,324],"class_list":["post-2491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas","tag-clodoaldo-pelissioni-es","tag-metro-de-san-pablo-es","tag-san-pablo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de cien kil\u00f3metros | Mobilitas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de cien kil\u00f3metros | Mobilitas\" \/>\n<meta property=\"og:description\" content=\"Sistema de metro de la ciudad de San Pablo debe terminar 2018 con m\u00e1s de cien kil\u00f3metros.\u00a0En 2010, la red de metro era de 68,9 kil\u00f3metros, alcanz\u00f3 los 77,4 kil\u00f3metros en 2015 y lleg\u00f3 a 80,4 kil\u00f3metros en agosto de 2018. La ciudad conta aun com 140 kil\u00f3metros del sistema de trenes metropolitanos. En operaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\" \/>\n<meta property=\"og:site_name\" content=\"Mobilitas\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-01T16:35:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-01T17:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Asquini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Asquini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\"},\"author\":{\"name\":\"Alexandre Asquini\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\"},\"headline\":\"M\u00e1s de cien kil\u00f3metros\",\"datePublished\":\"2018-10-01T16:35:10+00:00\",\"dateModified\":\"2018-10-01T17:19:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\"},\"wordCount\":1516,\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png\",\"keywords\":[\"CLODOALDO PELISSIONI\",\"METRO DE SAN PABLO\",\"SAN PABLO\"],\"articleSection\":[\"Notas\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\",\"url\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\",\"name\":\"M\u00e1s de cien kil\u00f3metros | Mobilitas\",\"isPartOf\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png\",\"datePublished\":\"2018-10-01T16:35:10+00:00\",\"dateModified\":\"2018-10-01T17:19:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage\",\"url\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png\",\"contentUrl\":\"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png\",\"width\":507,\"height\":265,\"caption\":\"Metr\u00f4 de S\u00e3o Paulo. Foto: Alexandre Carvalho, A2 IMG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobilitas.lat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de cien kil\u00f3metros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#website\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"name\":\"Mobilitas\",\"description\":\"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina\",\"publisher\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobilitas.lat\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#organization\",\"name\":\"OTM Editora\",\"url\":\"https:\/\/mobilitas.lat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"contentUrl\":\"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png\",\"width\":1200,\"height\":630,\"caption\":\"OTM Editora\"},\"image\":{\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d\",\"name\":\"Alexandre Asquini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g\",\"caption\":\"Alexandre Asquini\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de cien kil\u00f3metros | Mobilitas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de cien kil\u00f3metros | Mobilitas","og_description":"Sistema de metro de la ciudad de San Pablo debe terminar 2018 con m\u00e1s de cien kil\u00f3metros.\u00a0En 2010, la red de metro era de 68,9 kil\u00f3metros, alcanz\u00f3 los 77,4 kil\u00f3metros en 2015 y lleg\u00f3 a 80,4 kil\u00f3metros en agosto de 2018. La ciudad conta aun com 140 kil\u00f3metros del sistema de trenes metropolitanos. En operaci\u00f3n [&hellip;]","og_url":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/","og_site_name":"Mobilitas","article_published_time":"2018-10-01T16:35:10+00:00","article_modified_time":"2018-10-01T17:19:28+00:00","og_image":[{"width":507,"height":265,"url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png","type":"image\/png"}],"author":"Alexandre Asquini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexandre Asquini","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#article","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/"},"author":{"name":"Alexandre Asquini","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d"},"headline":"M\u00e1s de cien kil\u00f3metros","datePublished":"2018-10-01T16:35:10+00:00","dateModified":"2018-10-01T17:19:28+00:00","mainEntityOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/"},"wordCount":1516,"publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png","keywords":["CLODOALDO PELISSIONI","METRO DE SAN PABLO","SAN PABLO"],"articleSection":["Notas"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/","url":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/","name":"M\u00e1s de cien kil\u00f3metros | Mobilitas","isPartOf":{"@id":"https:\/\/mobilitas.lat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png","datePublished":"2018-10-01T16:35:10+00:00","dateModified":"2018-10-01T17:19:28+00:00","breadcrumb":{"@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#primaryimage","url":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png","contentUrl":"https:\/\/storage.mobilitas.lat\/uploads\/2018\/10\/MOBILITAS-ESTA\u00c7\u00c3O-HIGIEN\u00d3POLIS-MACKENZIE.png","width":507,"height":265,"caption":"Metr\u00f4 de S\u00e3o Paulo. Foto: Alexandre Carvalho, A2 IMG"},{"@type":"BreadcrumbList","@id":"https:\/\/mobilitas.lat\/es\/2018\/10\/01\/mais-de-cem-quilometros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobilitas.lat\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de cien kil\u00f3metros"}]},{"@type":"WebSite","@id":"https:\/\/mobilitas.lat\/es\/#website","url":"https:\/\/mobilitas.lat\/es\/","name":"Mobilitas","description":"Tecnologia e Mobilidade Urbana na Am\u00e9rica Latina","publisher":{"@id":"https:\/\/mobilitas.lat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobilitas.lat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/mobilitas.lat\/es\/#organization","name":"OTM Editora","url":"https:\/\/mobilitas.lat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","contentUrl":"https:\/\/mobilitas.lat\/wp-content\/uploads\/2024\/03\/opengraph.png","width":1200,"height":630,"caption":"OTM Editora"},"image":{"@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/cae0d01ccbe855d1858d146e4c4d582d","name":"Alexandre Asquini","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/mobilitas.lat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac99dbef1420f75cc7d86913eb8a7cdfbe13e2509ad7a45649a61414f6d2785?s=96&d=mm&r=g","caption":"Alexandre Asquini"}}]}},"_links":{"self":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/comments?post=2491"}],"version-history":[{"count":11,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2491\/revisions"}],"predecessor-version":[{"id":2512,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/posts\/2491\/revisions\/2512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media\/2486"}],"wp:attachment":[{"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/media?parent=2491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/categories?post=2491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobilitas.lat\/es\/wp-json\/wp\/v2\/tags?post=2491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}